{"id":2853,"date":"2022-08-24T14:27:00","date_gmt":"2022-08-24T14:27:00","guid":{"rendered":"https:\/\/tresoramschottentor.at\/index.php\/datenschutz\/"},"modified":"2024-08-30T09:09:08","modified_gmt":"2024-08-30T09:09:08","slug":"privacy","status":"publish","type":"page","link":"https:\/\/tresoramschottentor.at\/en\/privacy\/","title":{"rendered":"Datenschutz"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2853\" class=\"elementor elementor-2853 elementor-1496\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52121c0 e-flex e-con-boxed e-con e-parent\" data-id=\"52121c0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7f075dc e-flex e-con-boxed e-con e-child\" data-id=\"7f075dc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd3d4b4 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"bd3d4b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Datenschutz<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db08359 w-full elementor-widget elementor-widget-text-editor\" data-id=\"db08359\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"c394\" class=\"frame frame-default frame-type-text frame-layout-0\">\n<p>Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung der 24h Safe GmbH. Eine Nutzung der Internetseiten der 24h Safe GmbH ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung personenbezogener Daten erforderlich werden. Ist die Verarbeitung personenbezogener Daten erforderlich und besteht f\u00fcr eine solche Verarbeitung keine gesetzliche Grundlage, holen wir generell eine Einwilligung der betroffenen Person ein.<\/p>\n<\/p>\n<p>Die Verarbeitung personenbezogener Daten, beispielsweise des Namens, der Anschrift, E-Mail-Adresse oder Telefonnummer einer betroffenen Person, erfolgt stets im Einklang mit der Datenschutz-Grundverordnung und in \u00dcbereinstimmung mit den f\u00fcr die 24h Safe GmbH geltenden landesspezifischen Datenschutzbestimmungen. Mittels dieser Datenschutzerkl\u00e4rung m\u00f6chte unser Unternehmen die \u00d6ffentlichkeit \u00fcber Art, Umfang und Zweck der von uns erhobenen, genutzten und verarbeiteten personenbezogenen Daten informieren. Ferner werden betroffene Personen mittels dieser Datenschutzerkl\u00e4rung \u00fcber die ihnen zustehenden Rechte aufgekl\u00e4rt.<\/p>\n<\/p>\n<p>Die 24h Safe GmbH hat als f\u00fcr die Verarbeitung Verantwortlicher zahlreiche technische und organisatorische Ma\u00dfnahmen umgesetzt, um einen m\u00f6glichst l\u00fcckenlosen Schutz der \u00fcber diese Internetseite verarbeiteten personenbezogenen Daten sicherzustellen. Dennoch k\u00f6nnen Internetbasierte Daten\u00fcbertragungen grunds\u00e4tzlich Sicherheitsl\u00fccken aufweisen, sodass ein absoluter Schutz nicht gew\u00e4hrleistet werden kann. Aus diesem Grund steht es jeder betroffenen Person frei, personenbezogene Daten auch auf alternativen Wegen, beispielsweise telefonisch, an uns zu \u00fcbermitteln.<\/p>\n<\/p>\n<h3 style=\"color: #527d77; font-weight: 400; letter-spacing: 3px; font-family: 'EB Garamond' ,serif;\">1. Begriffsbestimmungen<\/h3>\n<p>Die Datenschutzerkl\u00e4rung der 24h Safe GmbH beruht auf den Begrifflichkeiten, die durch den Europ\u00e4ischen Richtlinien- und Verordnungsgeber beim Erlass der Datenschutz-Grundverordnung (DS-GVO) verwendet wurden. Unsere Datenschutzerkl\u00e4rung soll sowohl f\u00fcr die \u00d6ffentlichkeit als auch f\u00fcr unsere Kunden und Gesch\u00e4ftspartner einfach lesbar und verst\u00e4ndlich sein. Um dies zu gew\u00e4hrleisten, m\u00f6chten wir vorab die verwendeten Begrifflichkeiten erl\u00e4utern.<\/p>\n<\/p>\n<p>Wir verwenden in dieser Datenschutzerkl\u00e4rung unter anderem die folgenden Begriffe:<\/p>\n<\/p>\n<p>a) personenbezogene Daten<\/p>\n<\/p>\n<p>Personenbezogene Daten sind alle Informationen, die sich auf eine identifizierte oder identifizierbare nat\u00fcrliche Person (im Folgenden \u201ebetroffene Person\u201c) beziehen. Als identifizierbar wird eine nat\u00fcrliche Person angesehen, die direkt oder indirekt, insbesondere mittels Zuordnung zu einer Kennung wie einem Namen, zu einer Kennnummer, zu Standortdaten, zu einer Online-Kennung oder zu einem oder mehreren besonderen Merkmalen, die Ausdruck der physischen, physiologischen, genetischen, psychischen, wirtschaftlichen, kulturellen oder sozialen Identit\u00e4t dieser nat\u00fcrlichen Person sind, identifiziert werden kann.<\/p>\n<\/p>\n<p>b) betroffene Person<\/p>\n<\/p>\n<p>Betroffene Person ist jede identifizierte oder identifizierbare nat\u00fcrliche Person, deren personenbezogene Daten von dem f\u00fcr die Verarbeitung Verantwortlichen verarbeitet werden.<\/p>\n<\/p>\n<p>c) Verarbeitung<\/p>\n<\/p>\n<p>Verarbeitung ist jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\u00fchrte Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten wie das Erheben, das Erfassen, die Organisation, das Ordnen, die Speicherung, die Anpassung oder Ver\u00e4nderung, das Auslesen, das Abfragen, die Verwendung, die Offenlegung durch \u00dcbermittlung, Verbreitung oder eine andere Form der Bereitstellung, den Abgleich oder die Verkn\u00fcpfung, die Einschr\u00e4nkung, das L\u00f6schen oder die Vernichtung.<\/p>\n<\/p>\n<p>d) Einschr\u00e4nkung der Verarbeitung<\/p>\n<\/p>\n<p>Einschr\u00e4nkung der Verarbeitung ist die Markierung gespeicherter personenbezogener Daten mit dem Ziel, ihre k\u00fcnftige Verarbeitung einzuschr\u00e4nken.<\/p>\n<\/p>\n<p>e) Profiling<\/p>\n<\/p>\n<p>Profiling ist jede Art der automatisierten Verarbeitung personenbezogener Daten, die darin besteht, dass diese personenbezogenen Daten verwendet werden, um bestimmte pers\u00f6nliche Aspekte, die sich auf eine nat\u00fcrliche Person beziehen, zu bewerten, insbesondere, um Aspekte bez\u00fcglich Arbeitsleistung, wirtschaftlicher Lage, Gesundheit, pers\u00f6nlicher Vorlieben, Interessen, Zuverl\u00e4ssigkeit, Verhalten, Aufenthaltsort oder Ortswechsel dieser nat\u00fcrlichen Person zu analysieren oder vorherzusagen.<\/p>\n<\/p>\n<p>f) Pseudonymisierung<\/p>\n<\/p>\n<p>Pseudonymisierung ist die Verarbeitung personenbezogener Daten in einer Weise, auf welche die personenbezogenen Daten ohne Hinzuziehung zus\u00e4tzlicher Informationen nicht mehr einer spezifischen betroffenen Person zugeordnet werden k\u00f6nnen, sofern diese zus\u00e4tzlichen Informationen gesondert aufbewahrt werden und technischen und organisatorischen Ma\u00dfnahmen unterliegen, die gew\u00e4hrleisten, dass die personenbezogenen Daten nicht einer identifizierten oder identifizierbaren nat\u00fcrlichen Person zugewiesen werden.<\/p>\n<\/p>\n<p>g) Verantwortlicher oder f\u00fcr die Verarbeitung Verantwortlicher<\/p>\n<\/p>\n<p>Verantwortlicher oder f\u00fcr die Verarbeitung Verantwortlicher ist die nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten entscheidet. Sind die Zwecke und Mittel dieser Verarbeitung durch das Unionsrecht oder das Recht der Mitgliedstaaten vorgegeben, so kann der Verantwortliche beziehungsweise k\u00f6nnen die bestimmten Kriterien seiner Benennung nach dem Unionsrecht oder dem Recht der Mitgliedstaaten vorgesehen werden.<\/p>\n<\/p>\n<p>h) Auftragsverarbeiter<\/p>\n<\/p>\n<p>Auftragsverarbeiter ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die personenbezogene Daten im Auftrag des Verantwortlichen verarbeitet.<\/p>\n<\/p>\n<p>i) Empf\u00e4nger<\/p>\n<\/p>\n<p>Empf\u00e4nger ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, der personenbezogene Daten offengelegt werden, unabh\u00e4ngig davon, ob es sich bei ihr um einen Dritten handelt oder nicht. Beh\u00f6rden, die im Rahmen eines bestimmten Untersuchungsauftrags nach dem Unionsrecht oder dem Recht der Mitgliedstaaten m\u00f6glicherweise personenbezogene Daten erhalten, gelten jedoch nicht als Empf\u00e4nger.<\/p>\n<\/p>\n<p>j) Dritter<\/p>\n<\/p>\n<p>Dritter ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle au\u00dfer der betroffenen Person, dem Verantwortlichen, dem Auftragsverarbeiter und den Personen, die unter der unmittelbaren Verantwortung des Verantwortlichen oder des Auftragsverarbeiters befugt sind, die personenbezogenen Daten zu verarbeiten.<\/p>\n<\/p>\n<p>k) Einwilligung<\/p>\n<\/p>\n<p>Einwilligung ist jede von der betroffenen Person freiwillig f\u00fcr den bestimmten Fall in informierter Weise und unmissverst\u00e4ndlich abgegebene Willensbekundung in Form einer Erkl\u00e4rung oder einer sonstigen eindeutigen best\u00e4tigenden Handlung, mit der die betroffene Person zu verstehen gibt, dass sie mit der Verarbeitung der sie betreffenden personenbezogenen Daten einverstanden ist.<\/p>\n<\/p>\n<h3 style=\"color: #527d77; font-weight: 400; letter-spacing: 3px; font-family: 'EB Garamond' ,serif;\">2. Name und Anschrift des f\u00fcr die Verarbeitung Verantwortlichen<\/h3>\n<p>Verantwortlicher im Sinne der Datenschutz-Grundverordnung, sonstiger in den Mitgliedstaaten der Europ\u00e4ischen Union geltenden Datenschutzgesetze und anderer Bestimmungen mit datenschutzrechtlichem Charakter ist die:<\/p>\n<\/p>\n<p>24h Safe GmbH<br \/>Schottenring 2-6<br \/>A-1010 Wien<\/p>\n<\/p>\n<h3 style=\"color: #527d77; font-weight: 400; letter-spacing: 3px; font-family: 'EB Garamond' ,serif;\">3. Erfassung von allgemeinen Daten und Informationen<\/h3>\n<p>Die Internetseite der 24h Safe GmbH erfasst mit jedem Aufruf der Internetseite durch eine betroffene Person oder ein automatisiertes System eine Reihe von allgemeinen Daten und Informationen. Diese allgemeinen Daten und Informationen werden in den Logfiles des Servers gespeichert. Erfasst werden k\u00f6nnen die (1) verwendeten Browsertypen und Versionen, (2) das vom zugreifenden System verwendete Betriebssystem, (3) die Internetseite, von welcher ein zugreifendes System auf unsere Internetseite gelangt (sogenannte Referrer), (4) die Unterwebseiten, welche \u00fcber ein zugreifendes System auf unserer Internetseite angesteuert werden, (5) das Datum und die Uhrzeit eines Zugriffs auf die Internetseite, (6) eine Internet-Protokoll-Adresse (IP-Adresse), (7) der Internet-Service-Provider des zugreifenden Systems und (8) sonstige \u00e4hnliche Daten und Informationen, die der Gefahrenabwehr im Falle von Angriffen auf unsere informationstechnologischen Systeme dienen.<\/p>\n<\/p>\n<p>Bei der Nutzung dieser allgemeinen Daten und Informationen zieht die 24h Safe GmbH keine R\u00fcckschl\u00fcsse auf die betroffene Person. Diese Informationen werden vielmehr ben\u00f6tigt, um (1) die Inhalte unserer Internetseite korrekt auszuliefern, (2) die Inhalte unserer Internetseite sowie die Werbung f\u00fcr diese zu optimieren, (3) die dauerhafte Funktionsf\u00e4higkeit unserer informationstechnologischen Systeme und der Technik unserer Internetseite zu gew\u00e4hrleisten sowie (4) um Strafverfolgungsbeh\u00f6rden im Falle eines Cyberangriffes die zur Strafverfolgung notwendigen Informationen bereitzustellen. Diese anonym erhobenen Daten und Informationen werden durch die 24h Safe GmbH daher einerseits statistisch und ferner mit dem Ziel ausgewertet, den Datenschutz und die Datensicherheit in unserem Unternehmen zu erh\u00f6hen, um letztlich ein optimales Schutzniveau f\u00fcr die von uns verarbeiteten personenbezogenen Daten sicherzustellen. Die anonymen Daten der Server-Logfiles werden getrennt von allen durch eine betroffene Person angegebenen personenbezogenen Daten gespeichert.<\/p>\n<\/p>\n<h3 style=\"color: #527d77; font-weight: 400; letter-spacing: 3px; font-family: 'EB Garamond' ,serif;\">4. Routinem\u00e4\u00dfige L\u00f6schung und Sperrung von personenbezogenen Daten<\/h3>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche verarbeitet und speichert personenbezogene Daten der betroffenen Person nur f\u00fcr den Zeitraum, der zur Erreichung des Speicherungszwecks erforderlich ist oder sofern dies durch den Europ\u00e4ischen Richtlinien- und Verordnungsgeber oder einen anderen Gesetzgeber in Gesetzen oder Vorschriften, welchen der f\u00fcr die Verarbeitung Verantwortliche unterliegt, vorgesehen wurde.<\/p>\n<\/p>\n<p>Entf\u00e4llt der Speicherungszweck oder l\u00e4uft eine vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber oder einem anderen zust\u00e4ndigen Gesetzgeber vorgeschriebene Speicherfrist ab, werden die personenbezogenen Daten routinem\u00e4\u00dfig und entsprechend den gesetzlichen Vorschriften gesperrt oder gel\u00f6scht.<\/p>\n<\/p>\n<h3 style=\"color: #527d77; font-weight: 400; letter-spacing: 3px; font-family: 'EB Garamond' ,serif;\">5. Rechte der betroffenen Person<\/h3>\n<p>a) Recht auf Best\u00e4tigung<\/p>\n<\/p>\n<p>Jede betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber einger\u00e4umte Recht, von dem f\u00fcr die Verarbeitung Verantwortlichen eine Best\u00e4tigung dar\u00fcber zu verlangen, ob sie betreffende personenbezogene Daten verarbeitet werden. M\u00f6chte eine betroffene Person dieses Best\u00e4tigungsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an unseren Datenschutzbeauftragten oder einen anderen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/p>\n<\/p>\n<p>b) Recht auf Auskunft<\/p>\n<\/p>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, jederzeit von dem f\u00fcr die Verarbeitung Verantwortlichen unentgeltliche Auskunft \u00fcber die zu seiner Person gespeicherten personenbezogenen Daten und eine Kopie dieser Auskunft zu erhalten. Ferner hat der Europ\u00e4ische Richtlinien- und Verordnungsgeber der betroffenen Person Auskunft \u00fcber folgende Informationen zugestanden:<\/p>\n<\/p>\n<p>die Verarbeitungszwecke<\/p>\n<\/p>\n<p>die Kategorien personenbezogener Daten, die verarbeitet werden<\/p>\n<\/p>\n<p>die Empf\u00e4nger oder Kategorien von Empf\u00e4ngern, gegen\u00fcber denen die personenbezogenen Daten offengelegt worden sind oder noch offengelegt werden, insbesondere bei Empf\u00e4ngern in Drittl\u00e4ndern oder bei internationalen Organisationen<\/p>\n<\/p>\n<p>falls m\u00f6glich die geplante Dauer, f\u00fcr die die personenbezogenen Daten gespeichert werden, oder, falls dies nicht m\u00f6glich ist, die Kriterien f\u00fcr die Festlegung dieser Dauer<\/p>\n<\/p>\n<p>das Bestehen eines Rechts auf Berichtigung oder L\u00f6schung der sie betreffenden personenbezogenen Daten oder auf Einschr\u00e4nkung der Verarbeitung durch den Verantwortlichen oder eines Widerspruchsrechts gegen diese Verarbeitung<\/p>\n<\/p>\n<p>das Bestehen eines Beschwerderechts bei einer Aufsichtsbeh\u00f6rde<\/p>\n<\/p>\n<p>wenn die personenbezogenen Daten nicht bei der betroffenen Person erhoben werden: Alle verf\u00fcgbaren Informationen \u00fcber die Herkunft der Daten<\/p>\n<\/p>\n<p>das Bestehen einer automatisierten Entscheidungsfindung einschlie\u00dflich Profiling gem\u00e4\u00df Artikel 22 Abs.1 und 4 DS-GVO und \u2014 zumindest in diesen F\u00e4llen \u2014 aussagekr\u00e4ftige Informationen \u00fcber die involvierte Logik sowie die Tragweite und die angestrebten Auswirkungen einer derartigen Verarbeitung f\u00fcr die betroffene Person<\/p>\n<\/p>\n<p>Ferner steht der betroffenen Person ein Auskunftsrecht dar\u00fcber zu, ob personenbezogene Daten an ein Drittland oder an eine internationale Organisation \u00fcbermittelt wurden. Sofern dies der Fall ist, so steht der betroffenen Person im \u00dcbrigen das Recht zu, Auskunft \u00fcber die geeigneten Garantien im Zusammenhang mit der \u00dcbermittlung zu erhalten.<\/p>\n<\/p>\n<p>M\u00f6chte eine betroffene Person dieses Auskunftsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an unseren Datenschutzbeauftragten oder einen anderen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/p>\n<\/p>\n<p>c) Recht auf Berichtigung<\/p>\n<\/p>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, die unverz\u00fcgliche Berichtigung sie betreffender unrichtiger personenbezogener Daten zu verlangen. Ferner steht der betroffenen Person das Recht zu, unter Ber\u00fccksichtigung der Zwecke der Verarbeitung, die Vervollst\u00e4ndigung unvollst\u00e4ndiger personenbezogener Daten \u2014 auch mittels einer erg\u00e4nzenden Erkl\u00e4rung \u2014 zu verlangen.<\/p>\n<\/p>\n<p>M\u00f6chte eine betroffene Person dieses Berichtigungsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an unseren Datenschutzbeauftragten oder einen anderen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/p>\n<\/p>\n<p>d) Recht auf L\u00f6schung (Recht auf Vergessen werden)<\/p>\n<\/p>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, von dem Verantwortlichen zu verlangen, dass die sie betreffenden personenbezogenen Daten unverz\u00fcglich gel\u00f6scht werden, sofern einer der folgenden Gr\u00fcnde zutrifft und soweit die Verarbeitung nicht erforderlich ist:<\/p>\n<\/p>\n<p>Die personenbezogenen Daten wurden f\u00fcr solche Zwecke erhoben oder auf sonstige Weise verarbeitet, f\u00fcr welche sie nicht mehr notwendig sind.<\/p>\n<\/p>\n<p>Die betroffene Person widerruft ihre Einwilligung, auf die sich die Verarbeitung gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe a DS-GVO oder Art. 9 Abs. 2 Buchstabe a DS-GVO st\u00fctzte, und es fehlt an einer anderweitigen Rechtsgrundlage f\u00fcr die Verarbeitung.<\/p>\n<\/p>\n<p>Die betroffene Person legt gem\u00e4\u00df Art. 21 Abs. 1 DS-GVO Widerspruch gegen die Verarbeitung ein, und es liegen keine vorrangigen berechtigten Gr\u00fcnde f\u00fcr die Verarbeitung vor, oder die betroffene Person legt gem\u00e4\u00df Art. 21 Abs. 2 DS-GVO Widerspruch gegen die Verarbeitung ein.<\/p>\n<\/p>\n<p>Die personenbezogenen Daten wurden unrechtm\u00e4\u00dfig verarbeitet.<\/p>\n<\/p>\n<p>Die L\u00f6schung der personenbezogenen Daten ist zur Erf\u00fcllung einer rechtlichen Verpflichtung nach dem Unionsrecht oder dem Recht der Mitgliedstaaten erforderlich, dem der Verantwortliche unterliegt.<\/p>\n<\/p>\n<p>Die personenbezogenen Daten wurden in Bezug auf angebotene Dienste der Informationsgesellschaft gem\u00e4\u00df Art. 8 Abs. 1 DS-GVO erhoben.<\/p>\n<\/p>\n<p>Sofern einer der oben genannten Gr\u00fcnde zutrifft und eine betroffene Person die L\u00f6schung von personenbezogenen Daten, die bei der 24h Safe GmbH gespeichert sind, veranlassen m\u00f6chte, kann sie sich hierzu jederzeit an unseren Datenschutzbeauftragten oder einen anderen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden. Der Datenschutzbeauftragte der 24h Safe GmbH oder ein anderer Mitarbeiter wird veranlassen, dass dem L\u00f6schverlangen unverz\u00fcglich nachgekommen wird.<\/p>\n<\/p>\n<p>Wurden die personenbezogenen Daten von der 24h Safe GmbH \u00f6ffentlich gemacht und ist unser Unternehmen als Verantwortlicher gem\u00e4\u00df Art. 17 Abs. 1 DS-GVO zur L\u00f6schung der personenbezogenen Daten verpflichtet, so trifft die 24h Safe GmbH unter Ber\u00fccksichtigung der verf\u00fcgbaren Technologie und der Implementierungskosten angemessene Ma\u00dfnahmen, auch technischer Art, um andere f\u00fcr die Datenverarbeitung Verantwortliche, welche die ver\u00f6ffentlichten personenbezogenen Daten verarbeiten, dar\u00fcber in Kenntnis zu setzen, dass die betroffene Person von diesen anderen f\u00fcr die Datenverarbeitung Verantwortlichen die L\u00f6schung s\u00e4mtlicher Links zu diesen personenbezogenen Daten oder von Kopien oder Replikationen dieser personenbezogenen Daten verlangt hat, soweit die Verarbeitung nicht erforderlich ist. Der Datenschutzbeauftragte der 24h Safe GmbH oder ein anderer Mitarbeiter wird im Einzelfall das Notwendige veranlassen.<\/p>\n<\/p>\n<p>e) Recht auf Einschr\u00e4nkung der Verarbeitung<\/p>\n<\/p>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, von dem Verantwortlichen die Einschr\u00e4nkung der Verarbeitung zu verlangen, wenn eine der folgenden Voraussetzungen gegeben ist:<\/p>\n<\/p>\n<p>Die Richtigkeit der personenbezogenen Daten wird von der betroffenen Person bestritten, und zwar f\u00fcr eine Dauer, die es dem Verantwortlichen erm\u00f6glicht, die Richtigkeit der personenbezogenen Daten zu \u00fcberpr\u00fcfen.<\/p>\n<\/p>\n<p>Die Verarbeitung ist unrechtm\u00e4\u00dfig, die betroffene Person lehnt die L\u00f6schung der personenbezogenen Daten ab und verlangt stattdessen die Einschr\u00e4nkung der Nutzung der personenbezogenen Daten.<\/p>\n<\/p>\n<p>Der Verantwortliche ben\u00f6tigt die personenbezogenen Daten f\u00fcr die Zwecke der Verarbeitung nicht l\u00e4nger, die betroffene Person ben\u00f6tigt sie jedoch zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen.<\/p>\n<\/p>\n<p>Die betroffene Person hat Widerspruch gegen die Verarbeitung gem. Art. 21 Abs. 1 DS-GVO eingelegt und es steht noch nicht fest, ob die berechtigten Gr\u00fcnde des Verantwortlichen gegen\u00fcber denen der betroffenen Person \u00fcberwiegen.<\/p>\n<\/p>\n<p>Sofern eine der oben genannten Voraussetzungen gegeben ist und eine betroffene Person die Einschr\u00e4nkung von personenbezogenen Daten, die bei der 24h Safe GmbH gespeichert sind, verlangen m\u00f6chte, kann sie sich hierzu jederzeit an unseren Datenschutzbeauftragten oder einen anderen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden. Der Datenschutzbeauftragte der 24h Safe GmbH oder ein anderer Mitarbeiter wird die Einschr\u00e4nkung der Verarbeitung veranlassen.<\/p>\n<\/p>\n<p>f) Recht auf Daten\u00fcbertragbarkeit<\/p>\n<\/p>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, die sie betreffenden personenbezogenen Daten, welche durch die betroffene Person einem Verantwortlichen bereitgestellt wurden, in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten. Sie hat au\u00dferdem das Recht, diese Daten einem anderen Verantwortlichen ohne Behinderung durch den Verantwortlichen, dem die personenbezogenen Daten bereitgestellt wurden, zu \u00fcbermitteln, sofern die Verarbeitung auf der Einwilligung gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe a DS-GVO oder Art. 9 Abs. 2 Buchstabe a DS-GVO oder auf einem Vertrag gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe b DS-GVO beruht und die Verarbeitung mithilfe automatisierter Verfahren erfolgt, sofern die Verarbeitung nicht f\u00fcr die Wahrnehmung einer Aufgabe erforderlich ist, die im \u00f6ffentlichen Interesse liegt oder in Aus\u00fcbung \u00f6ffentlicher Gewalt erfolgt, welche dem Verantwortlichen \u00fcbertragen wurde.<\/p>\n<\/p>\n<p>Ferner hat die betroffene Person bei der Aus\u00fcbung ihres Rechts auf Daten\u00fcbertragbarkeit gem\u00e4\u00df Art. 20 Abs. 1 DS-GVO das Recht, zu erwirken, dass die personenbezogenen Daten direkt von einem Verantwortlichen an einen anderen Verantwortlichen \u00fcbermittelt werden, soweit dies technisch machbar ist und sofern hiervon nicht die Rechte und Freiheiten anderer Personen beeintr\u00e4chtigt werden.<\/p>\n<\/p>\n<p>Zur Geltendmachung des Rechts auf Daten\u00fcbertragbarkeit kann sich die betroffene Person jederzeit an den von der 24h Safe GmbH bestellten Datenschutzbeauftragten oder einen anderen Mitarbeiter wenden.<\/p>\n<\/p>\n<p>g) Recht auf Widerspruch<\/p>\n<\/p>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, aus Gr\u00fcnden, die sich aus ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung sie betreffender personenbezogener Daten, die aufgrund von Art. 6 Abs. 1 Buchstaben e oder f DS-GVO erfolgt, Widerspruch einzulegen. Dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling.<\/p>\n<\/p>\n<p>Die 24h Safe GmbH verarbeitet die personenbezogenen Daten im Falle des Widerspruchs nicht mehr, es sei denn, wir k\u00f6nnen zwingende schutzw\u00fcrdige Gr\u00fcnde f\u00fcr die Verarbeitung nachweisen, die den Interessen, Rechten und Freiheiten der betroffenen Person \u00fcberwiegen, oder die Verarbeitung dient der Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen.<\/p>\n<\/p>\n<p>Verarbeitet die 24h Safe GmbH personenbezogene Daten, um Direktwerbung zu betreiben, so hat die betroffene Person das Recht, jederzeit Widerspruch gegen die Verarbeitung der personenbezogenen Daten zum Zwecke derartiger Werbung einzulegen. Dies gilt auch f\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht. Widerspricht die betroffene Person gegen\u00fcber der 24h Safe GmbH der Verarbeitung f\u00fcr Zwecke der Direktwerbung, so wird die 24h Safe GmbH die personenbezogenen Daten nicht mehr f\u00fcr diese Zwecke verarbeiten.<\/p>\n<\/p>\n<p>Zudem hat die betroffene Person das Recht, aus Gr\u00fcnden, die sich aus ihrer besonderen Situation ergeben, gegen die sie betreffende Verarbeitung personenbezogener Daten, die bei der 24h Safe GmbH zu wissenschaftlichen oder historischen Forschungszwecken oder zu statistischen Zwecken gem\u00e4\u00df Art. 89 Abs. 1 DS-GVO erfolgen, Widerspruch einzulegen, es sei denn, eine solche Verarbeitung ist zur Erf\u00fcllung einer im \u00f6ffentlichen Interesse liegenden Aufgabe erforderlich.<\/p>\n<\/p>\n<p>Zur Aus\u00fcbung des Rechts auf Widerspruch kann sich die betroffene Person direkt an den Datenschutzbeauftragten der 24h Safe GmbH oder einen anderen Mitarbeiter wenden. Der betroffenen Person steht es ferner frei, im Zusammenhang mit der Nutzung von Diensten der Informationsgesellschaft, ungeachtet der Richtlinie 2002\/58\/EG, ihr Widerspruchsrecht mittels automatisierter Verfahren auszu\u00fcben, bei denen technische Spezifikationen verwendet werden.<\/p>\n<\/p>\n<p>h) Automatisierte Entscheidungen im Einzelfall einschlie\u00dflich Profiling<\/p>\n<\/p>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, nicht einer ausschlie\u00dflich auf einer automatisierten Verarbeitung \u2014 einschlie\u00dflich Profiling \u2014 beruhenden Entscheidung unterworfen zu werden, die ihr gegen\u00fcber rechtliche Wirkung entfaltet oder sie in \u00e4hnlicher Weise erheblich beeintr\u00e4chtigt, sofern die Entscheidung (1) nicht f\u00fcr den Abschluss oder die Erf\u00fcllung eines Vertrags zwischen der betroffenen Person und dem Verantwortlichen erforderlich ist, oder (2) aufgrund von Rechtsvorschriften der Union oder der Mitgliedstaaten, denen der Verantwortliche unterliegt, zul\u00e4ssig ist und diese Rechtsvorschriften angemessene Ma\u00dfnahmen zur Wahrung der Rechte und Freiheiten sowie der berechtigten Interessen der betroffenen Person enthalten oder (3) mit ausdr\u00fccklicher Einwilligung der betroffenen Person erfolgt.<\/p>\n<\/p>\n<p>Ist die Entscheidung (1) f\u00fcr den Abschluss oder die Erf\u00fcllung eines Vertrags zwischen der betroffenen Person und dem Verantwortlichen erforderlich oder (2) erfolgt sie mit ausdr\u00fccklicher Einwilligung der betroffenen Person, trifft die 24h Safe GmbH angemessene Ma\u00dfnahmen, um die Rechte und Freiheiten sowie die berechtigten Interessen der betroffenen Person zu wahren, wozu mindestens das Recht auf Erwirkung des Eingreifens einer Person seitens des Verantwortlichen, auf Darlegung des eigenen Standpunkts und auf Anfechtung der Entscheidung geh\u00f6rt.<\/p>\n<\/p>\n<p>M\u00f6chte die betroffene Person Rechte mit Bezug auf automatisierte Entscheidungen geltend machen, kann sie sich hierzu jederzeit an unseren Datenschutzbeauftragten oder einen anderen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/p>\n<\/p>\n<p>i) Recht auf Widerruf einer datenschutzrechtlichen Einwilligung<\/p>\n<\/p>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, eine Einwilligung zur Verarbeitung personenbezogener Daten jederzeit zu widerrufen.<\/p>\n<\/p>\n<p>M\u00f6chte die betroffene Person ihr Recht auf Widerruf einer Einwilligung geltend machen, kann sie sich hierzu jederzeit an unseren Datenschutzbeauftragten oder einen anderen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/p>\n<\/p>\n<h3 style=\"color: #527d77; font-weight: 400; letter-spacing: 3px; font-family: 'EB Garamond' ,serif;\">6. Datenschutz bei Bewerbungen und im Bewerbungsverfahren<\/h3>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche erhebt und verarbeitet die personenbezogenen Daten von Bewerbern zum Zwecke der Abwicklung des Bewerbungsverfahrens. Die Verarbeitung kann auch auf elektronischem Wege erfolgen. Dies ist insbesondere dann der Fall, wenn ein Bewerber entsprechende Bewerbungsunterlagen auf dem elektronischen Wege, beispielsweise per E-Mail oder \u00fcber ein auf der Internetseite befindliches Webformular, an den f\u00fcr die Verarbeitung Verantwortlichen \u00fcbermittelt. Schlie\u00dft der f\u00fcr die Verarbeitung Verantwortliche einen Anstellungsvertrag mit einem Bewerber, werden die \u00fcbermittelten Daten zum Zwecke der Abwicklung des Besch\u00e4ftigungsverh\u00e4ltnisses unter Beachtung der gesetzlichen Vorschriften gespeichert. Wird von dem f\u00fcr die Verarbeitung Verantwortlichen kein Anstellungsvertrag mit dem Bewerber geschlossen, so werden die Bewerbungsunterlagen zwei Monate nach Bekanntgabe der Absageentscheidung automatisch gel\u00f6scht, sofern einer L\u00f6schung keine sonstigen berechtigten Interessen des f\u00fcr die Verarbeitung Verantwortlichen entgegenstehen. Sonstiges berechtigtes Interesse in diesem Sinne ist beispielsweise eine Beweispflicht in einem Verfahren nach dem Allgemeinen Gleichbehandlungsgesetz (AGG).<\/p>\n<\/p>\n<h3 style=\"color: #527d77; font-weight: 400; letter-spacing: 3px; font-family: 'EB Garamond' ,serif;\">7. Datenschutzbestimmungen zu Einsatz und Verwendung von Facebook<\/h3>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten des Unternehmens Facebook integriert. Facebook ist ein soziales Netzwerk.<\/p>\n<\/p>\n<p>Ein soziales Netzwerk ist ein im Internet betriebener sozialer Treffpunkt, eine Online-Gemeinschaft, die es den Nutzern in der Regel erm\u00f6glicht, untereinander zu kommunizieren und im virtuellen Raum zu interagieren. Ein soziales Netzwerk kann als Plattform zum Austausch von Meinungen und Erfahrungen dienen oder erm\u00f6glicht es der Internetgemeinschaft, pers\u00f6nliche oder unternehmensbezogene Informationen bereitzustellen. Facebook erm\u00f6glicht den Nutzern des sozialen Netzwerkes unter anderem die Erstellung von privaten Profilen, den Upload von Fotos und eine Vernetzung \u00fcber Freundschaftsanfragen.<\/p>\n<\/p>\n<p>Betreibergesellschaft von Facebook ist die Facebook, Inc., 1 Hacker Way, Menlo Park, CA 94025, USA. F\u00fcr die Verarbeitung personenbezogener Daten Verantwortlicher ist, wenn eine betroffene Person au\u00dferhalb der USA oder Kanada lebt, die Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Ireland.<\/p>\n<\/p>\n<p>Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Facebook-Komponente (Facebook-Plug-In) integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Facebook-Komponente veranlasst, eine Darstellung der entsprechenden Facebook-Komponente von Facebook herunterzuladen. Eine Gesamt\u00fcbersicht \u00fcber alle Facebook-Plug-Ins kann unter developers.facebook.com\/docs\/plugins\/ abgerufen werden. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Facebook Kenntnis dar\u00fcber, welche konkrete Unterseite unserer Internetseite durch die betroffene Person besucht wird.<\/p>\n<\/p>\n<p>Sofern die betroffene Person gleichzeitig bei Facebook eingeloggt ist, erkennt Facebook mit jedem Aufruf unserer Internetseite durch die betroffene Person und w\u00e4hrend der gesamten Dauer des jeweiligen Aufenthaltes auf unserer Internetseite, welche konkrete Unterseite unserer Internetseite die betroffene Person besucht. Diese Informationen werden durch die Facebook-Komponente gesammelt und durch Facebook dem jeweiligen Facebook-Account der betroffenen Person zugeordnet. Bet\u00e4tigt die betroffene Person einen der auf unserer Internetseite integrierten Facebook-Buttons, beispielsweise den \u201eGef\u00e4llt mir\u201c-Button, oder gibt die betroffene Person einen Kommentar ab, ordnet Facebook diese Information dem pers\u00f6nlichen Facebook-Benutzerkonto der betroffenen Person zu und speichert diese personenbezogenen Daten.<\/p>\n<\/p>\n<p>Facebook erh\u00e4lt \u00fcber die Facebook-Komponente immer dann eine Information dar\u00fcber, dass die betroffene Person unsere Internetseite besucht hat, wenn die betroffene Person zum Zeitpunkt des Aufrufs unserer Internetseite gleichzeitig bei Facebook eingeloggt ist; dies findet unabh\u00e4ngig davon statt, ob die betroffene Person die Facebook-Komponente anklickt oder nicht. Ist eine derartige \u00dcbermittlung dieser Informationen an Facebook von der betroffenen Person nicht gewollt, kann diese die \u00dcbermittlung dadurch verhindern, dass sie sich vor einem Aufruf unserer Internetseite aus ihrem Facebook-Account ausloggt.<\/p>\n<\/p>\n<p>Die von Facebook ver\u00f6ffentlichte Datenrichtlinie, die unter de-de.facebook.com\/about\/privacy\/ abrufbar ist, gibt Aufschluss \u00fcber die Erhebung, Verarbeitung und Nutzung personenbezogener Daten durch Facebook. Ferner wird dort erl\u00e4utert, welche Einstellungsm\u00f6glichkeiten Facebook zum Schutz der Privatsph\u00e4re der betroffenen Person bietet. Zudem sind unterschiedliche Applikationen erh\u00e4ltlich, die es erm\u00f6glichen, eine Daten\u00fcbermittlung an Facebook zu unterdr\u00fccken, beispielsweise der Facebook-Blocker des Anbieters Webgraph, der unter webgraph.com\/resources\/facebookblocker\/ beschafft werden kann. Solche Applikationen k\u00f6nnen durch die betroffene Person genutzt werden, um eine Daten\u00fcbermittlung an Facebook zu unterdr\u00fccken.<\/p>\n<\/p>\n<h3 style=\"color: #527d77; font-weight: 400; letter-spacing: 3px; font-family: 'EB Garamond' ,serif;\">8. Datenschutzbestimmungen zu Einsatz und Verwendung von Google Analytics (mit Anonymisierungsfunktion)<\/h3>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite die Komponente Google Analytics (mit Anonymisierungsfunktion) integriert. Google Analytics ist ein Web-Analyse-Dienst. Web-Analyse ist die Erhebung, Sammlung und Auswertung von Daten \u00fcber das Verhalten von Besuchern von Internetseiten. Ein Web-Analyse-Dienst erfasst unter anderem Daten dar\u00fcber, von welcher Internetseite eine betroffene Person auf eine Internetseite gekommen ist (sogenannte Referrer), auf welche Unterseiten der Internetseite zugegriffen oder wie oft und f\u00fcr welche Verweildauer eine Unterseite betrachtet wurde. Eine Web-Analyse wird \u00fcberwiegend zur Optimierung einer Internetseite und zur Kosten-Nutzen-Analyse von Internetwerbung eingesetzt.<\/p>\n<\/p>\n<p>Betreibergesellschaft der Google-Analytics-Komponente ist die Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland.<\/p>\n<\/p>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche verwendet f\u00fcr die Web-Analyse \u00fcber Google Analytics den Zusatz &#8220;_gat._anonymizeIp&#8221;. Mittels dieses Zusatzes wird die IP-Adresse des Internetanschlusses der betroffenen Person von Google gek\u00fcrzt und anonymisiert, wenn der Zugriff auf unsere Internetseiten aus einem Mitgliedstaat der Europ\u00e4ischen Union oder aus einem anderen Vertragsstaat des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum erfolgt.<\/p>\n<\/p>\n<p>Der Zweck der Google-Analytics-Komponente ist die Analyse der Besucherstr\u00f6me auf unserer Internetseite. Google nutzt die gewonnenen Daten und Informationen unter anderem dazu, die Nutzung unserer Internetseite auszuwerten, um f\u00fcr uns Online-Reports, welche die Aktivit\u00e4ten auf unseren Internetseiten aufzeigen, zusammenzustellen, und um weitere mit der Nutzung unserer Internetseite in Verbindung stehende Dienstleistungen zu erbringen.<\/p>\n<\/p>\n<p>Google Analytics setzt ein Cookie auf dem informationstechnologischen System der betroffenen Person. Was Cookies sind, wurde oben bereits erl\u00e4utert. Mit Setzung des Cookies wird Google eine Analyse der Benutzung unserer Internetseite erm\u00f6glicht. Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Google-Analytics-Komponente integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Google-Analytics-Komponente veranlasst, Daten zum Zwecke der Online-Analyse an Google zu \u00fcbermitteln. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Google Kenntnis \u00fcber personenbezogene Daten, wie der IP-Adresse der betroffenen Person, die Google unter anderem dazu dienen, die Herkunft der Besucher und Klicks nachzuvollziehen und in der Folge Provisionsabrechnungen zu erm\u00f6glichen.<\/p>\n<\/p>\n<p>Mittels des Cookies werden personenbezogene Informationen, beispielsweise die Zugriffszeit, der Ort, von welchem ein Zugriff ausging und die H\u00e4ufigkeit der Besuche unserer Internetseite durch die betroffene Person, gespeichert. Bei jedem Besuch unserer Internetseiten werden diese personenbezogenen Daten, einschlie\u00dflich der IP-Adresse des von der betroffenen Person genutzten Internetanschlusses, an Google in den Vereinigten Staaten von Amerika \u00fcbertragen. Diese personenbezogenen Daten werden durch Google in den Vereinigten Staaten von Amerika gespeichert. Google gibt diese \u00fcber das technische Verfahren erhobenen personenbezogenen Daten unter Umst\u00e4nden an Dritte weiter.<\/p>\n<\/p>\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass Google ein Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem kann ein von Google Analytics bereits gesetzter Cookie jederzeit \u00fcber den Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<\/p>\n<\/p>\n<p>Ferner besteht f\u00fcr die betroffene Person die M\u00f6glichkeit, einer Erfassung der durch Google Analytics erzeugten, auf eine Nutzung dieser Internetseite bezogenen Daten sowie der Verarbeitung dieser Daten durch Google zu widersprechen und eine solche zu verhindern. Hierzu muss die betroffene Person ein Browser-Add-On unter dem Link tools.google.com\/dlpage\/gaoptout herunterladen und installieren. Dieses Browser-Add-On teilt Google Analytics \u00fcber JavaScript mit, dass keine Daten und Informationen zu den Besuchen von Internetseiten an Google Analytics \u00fcbermittelt werden d\u00fcrfen. Die Installation des Browser-Add-Ons wird von Google als Widerspruch gewertet. Wird das informationstechnologische System der betroffenen Person zu einem sp\u00e4teren Zeitpunkt gel\u00f6scht, formatiert oder neu installiert, muss durch die betroffene Person eine erneute Installation des Browser-Add-Ons erfolgen, um Google Analytics zu deaktivieren. Sofern das Browser-Add-On durch die betroffene Person oder einer anderen Person, die ihrem Machtbereich zuzurechnen ist, deinstalliert oder deaktiviert wird, besteht die M\u00f6glichkeit der Neuinstallation oder der erneuten Aktivierung des Browser-Add-Ons.<\/p>\n<\/p>\n<p>Weitere Informationen und die geltenden Datenschutzbestimmungen von Google k\u00f6nnen unter www.google.de\/intl\/de\/policies\/privacy\/ und unter www.google.com\/analytics\/terms\/de.html abgerufen werden. Google Analytics wird unter diesem Link www.google.com\/intl\/de_de\/analytics\/ genauer erl\u00e4utert.<\/p>\n<\/p>\n<h3 style=\"color: #527d77; font-weight: 400; letter-spacing: 3px; font-family: 'EB Garamond' ,serif;\">9. Datenschutzbestimmungen zu Einsatz und Verwendung von Google-Ads<\/h3>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Google Ads integriert. Google Ads ist ein Dienst zur Internetwerbung, der es Werbetreibenden gestattet, sowohl Anzeigen in den Suchmaschinenergebnissen von Google als auch im Google-Werbenetzwerk zu schalten. Google Ads erm\u00f6glicht es einem Werbetreibenden, vorab bestimmte Schl\u00fcsselw\u00f6rter festzulegen, mittels derer eine Anzeige in den Suchmaschinenergebnissen von Google ausschlie\u00dflich dann angezeigt wird, wenn der Nutzer mit der Suchmaschine ein schl\u00fcsselwortrelevantes Suchergebnis abruft. Im Google-Werbenetzwerk werden die Anzeigen mittels eines automatischen Algorithmus und unter Beachtung der zuvor festgelegten Schl\u00fcsselw\u00f6rter auf themenrelevanten Internetseiten verteilt.<\/p>\n<\/p>\n<p>Betreibergesellschaft der Dienste von Google Ads ist die Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland.<\/p>\n<\/p>\n<p>Der Zweck von Google Ads ist die Bewerbung unserer Internetseite durch die Einblendung von interessenrelevanter Werbung auf den Internetseiten von Drittunternehmen und in den Suchmaschinenergebnissen der Suchmaschine Google und eine Einblendung von Fremdwerbung auf unserer Internetseite.<\/p>\n<\/p>\n<p>Gelangt eine betroffene Person \u00fcber eine Google-Anzeige auf unsere Internetseite, wird auf dem informationstechnologischen System der betroffenen Person durch Google ein sogenannter Conversion-Cookie abgelegt. Was Cookies sind, wurde oben bereits erl\u00e4utert. Ein Conversion-Cookie verliert nach drei\u00dfig Tagen seine G\u00fcltigkeit und dient nicht zur Identifikation der betroffenen Person. \u00dcber den Conversion-Cookie wird, sofern das Cookie noch nicht abgelaufen ist, nachvollzogen, ob bestimmte Unterseiten, beispielsweise der Warenkorb von einem Online-Shop-System, auf unserer Internetseite aufgerufen wurden. Durch den Conversion-Cookie k\u00f6nnen sowohl wir als auch Google nachvollziehen, ob eine betroffene Person, die \u00fcber eine Ads-Anzeige auf unsere Internetseite gelangt ist, einen Umsatz generierte, also einen Warenkauf vollzogen oder abgebrochen hat.<\/p>\n<\/p>\n<p>Die durch die Nutzung des Conversion-Cookies erhobenen Daten und Informationen werden von Google verwendet, um Besuchsstatistiken f\u00fcr unsere Internetseite zu erstellen. Diese Besuchsstatistiken werden durch uns wiederum genutzt, um die Gesamtanzahl der Nutzer zu ermitteln, welche \u00fcber Ads-Anzeigen an uns vermittelt wurden, also um den Erfolg oder Misserfolg der jeweiligen Ads-Anzeige zu ermitteln und um unsere Ads-Anzeigen f\u00fcr die Zukunft zu optimieren. Weder unser Unternehmen noch andere Werbekunden von Google-Ads erhalten Informationen von Google, mittels derer die betroffene Person identifiziert werden k\u00f6nnte.<\/p>\n<\/p>\n<p>Mittels des Conversion-Cookies werden personenbezogene Informationen, beispielsweise die durch die betroffene Person besuchten Internetseiten, gespeichert. Bei jedem Besuch unserer Internetseiten werden demnach personenbezogene Daten, einschlie\u00dflich der IP-Adresse des von der betroffenen Person genutzten Internetanschlusses, an Google in den Vereinigten Staaten von Amerika \u00fcbertragen. Diese personenbezogenen Daten werden durch Google in den Vereinigten Staaten von Amerika gespeichert. Google gibt diese \u00fcber das technische Verfahren erhobenen personenbezogenen Daten unter Umst\u00e4nden an Dritte weiter.<\/p>\n<\/p>\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass Google einen Conversion-Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem kann ein von Google Ads bereits gesetzter Cookie jederzeit \u00fcber den Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<\/p>\n<\/p>\n<p>Ferner besteht f\u00fcr die betroffene Person die M\u00f6glichkeit, der interessenbezogenen Werbung durch Google zu widersprechen. Hierzu muss die betroffene Person von jedem der von ihr genutzten Internetbrowser aus den Link www.google.de\/settings\/ads aufrufen und dort die gew\u00fcnschten Einstellungen vornehmen.<\/p>\n<\/p>\n<p>Weitere Informationen und die geltenden Datenschutzbestimmungen von Google k\u00f6nnen unter www.google.de\/intl\/de\/policies\/privacy\/ abgerufen werden.<\/p>\n<\/p>\n<h3 style=\"color: #527d77; font-weight: 400; letter-spacing: 3px; font-family: 'EB Garamond' ,serif;\">10. Datenschutzbestimmungen zu Einsatz und Verwendung von Instagram<\/h3>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten des Dienstes Instagram integriert. Instagram ist ein Dienst, der als audiovisuelle Plattform zu qualifizieren ist und den Nutzern das Teilen von Fotos und Videos und zudem eine Weiterverbreitung solcher Daten in anderen sozialen Netzwerken erm\u00f6glicht.<\/p>\n<\/p>\n<p>Betreibergesellschaft der Dienste von Instagram ist die Instagram LLC, 1 Hacker Way, Building 14 First Floor, Menlo Park, CA, USA.<\/p>\n<\/p>\n<p>Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Instagram-Komponente (Insta-Button) integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Instagram-Komponente veranlasst, eine Darstellung der entsprechenden Komponente von Instagram herunterzuladen. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Instagram Kenntnis dar\u00fcber, welche konkrete Unterseite unserer Internetseite durch die betroffene Person besucht wird.<\/p>\n<\/p>\n<p>Sofern die betroffene Person gleichzeitig bei Instagram eingeloggt ist, erkennt Instagram mit jedem Aufruf unserer Internetseite durch die betroffene Person und w\u00e4hrend der gesamten Dauer des jeweiligen Aufenthaltes auf unserer Internetseite, welche konkrete Unterseite die betroffene Person besucht. Diese Informationen werden durch die Instagram-Komponente gesammelt und durch Instagram dem jeweiligen Instagram-Account der betroffenen Person zugeordnet. Bet\u00e4tigt die betroffene Person einen der auf unserer Internetseite integrierten Instagram-Buttons, werden die damit \u00fcbertragenen Daten und Informationen dem pers\u00f6nlichen Instagram-Benutzerkonto der betroffenen Person zugeordnet und von Instagram gespeichert und verarbeitet.<\/p>\n<\/p>\n<p>Instagram erh\u00e4lt \u00fcber die Instagram-Komponente immer dann eine Information dar\u00fcber, dass die betroffene Person unsere Internetseite besucht hat, wenn die betroffene Person zum Zeitpunkt des Aufrufs unserer Internetseite gleichzeitig bei Instagram eingeloggt ist; dies findet unabh\u00e4ngig davon statt, ob die betroffene Person die Instagram-Komponente anklickt oder nicht. Ist eine derartige \u00dcbermittlung dieser Informationen an Instagram von der betroffenen Person nicht gewollt, kann diese die \u00dcbermittlung dadurch verhindern, dass sie sich vor einem Aufruf unserer Internetseite aus ihrem Instagram-Account ausloggt.<\/p>\n<\/p>\n<p>Weitere Informationen und die geltenden Datenschutzbestimmungen von Instagram k\u00f6nnen unter <a href=\"http:\/\/help.instagram.com\/155833707900388\" target=\"_blank\" rel=\"noreferrer noopener\">help.instagram.com\/155833707900388<\/a> und <a href=\"http:\/\/www.instagram.com\/about\/legal\/privacy\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.instagram.com\/about\/legal\/privacy\/<\/a> abgerufen werden.<\/p>\n<\/p>\n<h3 style=\"color: #527d77; font-weight: 400; letter-spacing: 3px; font-family: 'EB Garamond' ,serif;\">11. Cookies<\/h3>\n<p>Wir verwenden Cookies, um Inhalte und Anzeigen zu personalisieren, Funktionen f\u00fcr soziale Medien anbieten zu k\u00f6nnen und die Zugriffe auf unserer Website zu analysieren. Au\u00dferdem geben wir Informationen zu Ihrer Verwendung unserer Website an unsere Partner f\u00fcr soziale Medien, Werbung und Analysen weiter. Unsere Partner f\u00fchren diese Informationen m\u00f6glicherweise mit weiteren Daten zusammen, die Sie ihnen bereitgestellt haben oder die sie im Rahmen Ihrer Nutzung der Dienste gesammelt haben.<\/p>\n<\/p>\n<p>Cookies sind kleine Textdateien, die von Webseiten verwendet werden, um die Benutzererfahrung effizienter zu gestelaten. Laut Gesetz k\u00f6nnen wir Cookies auf Ihrem Ger\u00e4t speichern, wenn diese f\u00fcr den Betrieb dieser Seite unbedingt notwendig sind. F\u00fcr alle anderen Cookie &#8211; Typen ben\u00f6tigen wir Ihre Erlaubnis. Diese Seite verwendet unterschiedliche Cookie &#8211; Typen. Einige Cookies werden von Drittparteien platziert, die auf unserer Seite erscheinen.Sie k\u00f6nnen Ihre Einwilligung jederzeit von der Cookie &#8211; Erkl\u00e4rung auf unserer Website \u00e4ndern oder wiederrufen. Erfahren Sie mehr in unserer Dateschutzrichtlinie mehr dar\u00fcber, wer wir sind, wie Sie uns kontaktieren k\u00f6nnen und wie wir personenbezogene Daten verarbeiten.<\/p>\n<\/p>\n<p>Ihre Einwilligung trifft auf die folgenden Domains zu: tresoramschottentor.at<\/p>\n<\/p>\n<\/div>\n<div id=\"c493\" class=\"frame frame-default frame-type-text frame-layout-0\">\n<h3 style=\"color: #527d77; font-weight: 400; letter-spacing: 3px; font-family: 'EB Garamond' ,serif;\">12. Rechtsgrundlage der Verarbeitung<\/h3>\n<p>Art. 6 I lit. a DS-GVO dient unserem Unternehmen als Rechtsgrundlage f\u00fcr Verarbeitungsvorg\u00e4nge, bei denen wir eine Einwilligung f\u00fcr einen bestimmten Verarbeitungszweck einholen. Ist die Verarbeitung personenbezogener Daten zur Erf\u00fcllung eines Vertrags, dessen Vertragspartei die betroffene Person ist, erforderlich, wie dies beispielsweise bei Verarbeitungsvorg\u00e4ngen der Fall ist, die f\u00fcr eine Lieferung von Waren oder die Erbringung einer sonstigen Leistung oder Gegenleistung notwendig sind, so beruht die Verarbeitung auf Art. 6 I lit. b DS-GVO. Gleiches gilt f\u00fcr solche Verarbeitungsvorg\u00e4nge die zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich sind, etwa in F\u00e4llen von Anfragen zur unseren Produkten oder Leistungen. Unterliegt unser Unternehmen einer rechtlichen Verpflichtung durch welche eine Verarbeitung von personenbezogenen Daten erforderlich wird, wie beispielsweise zur Erf\u00fcllung steuerlicher Pflichten, so basiert die Verarbeitung auf Art. 6 I lit. c DS-GVO. In seltenen F\u00e4llen k\u00f6nnte die Verarbeitung von personenbezogenen Daten erforderlich werden, um lebenswichtige Interessen der betroffenen Person oder einer anderen nat\u00fcrlichen Person zu sch\u00fctzen. Dies w\u00e4re beispielsweise der Fall, wenn ein Besucher in unserem Betrieb verletzt werden w\u00fcrde und daraufhin sein Name, sein Alter, seine Krankenkassendaten oder sonstige lebenswichtige Informationen an einen Arzt, ein Krankenhaus oder sonstige Dritte weitergegeben werden m\u00fcssten. Dann w\u00fcrde die Verarbeitung auf Art. 6 I lit. d DS-GVO beruhen. Letztlich k\u00f6nnten Verarbeitungsvorg\u00e4nge auf Art. 6 I lit. f DS-GVO beruhen. Auf dieser Rechtsgrundlage basieren Verarbeitungsvorg\u00e4nge, die von keiner der vorgenannten Rechtsgrundlagen erfasst werden, wenn die Verarbeitung zur Wahrung eines berechtigten Interesses unseres Unternehmens oder eines Dritten erforderlich ist, sofern die Interessen, Grundrechte und Grundfreiheiten des Betroffenen nicht \u00fcberwiegen. Solche Verarbeitungsvorg\u00e4nge sind uns insbesondere deshalb gestattet, weil sie durch den Europ\u00e4ischen Gesetzgeber besonders erw\u00e4hnt wurden. Er vertrat insoweit die Auffassung, dass ein berechtigtes Interesse anzunehmen sein k\u00f6nnte, wenn die betroffene Person ein Kunde des Verantwortlichen ist (Erw\u00e4gungsgrund 47 Satz 2 DS-GVO).<\/p>\n<\/p>\n<h3 style=\"color: #527d77; font-weight: 400; letter-spacing: 3px; font-family: 'EB Garamond' ,serif;\">13. Berechtigte Interessen an der Verarbeitung, die von dem Verantwortlichen oder einem Dritten verfolgt werden<\/h3>\n<p>Basiert die Verarbeitung personenbezogener Daten auf Artikel 6 I lit. f DS-GVO ist unser berechtigtes Interesse die Durchf\u00fchrung unserer Gesch\u00e4ftst\u00e4tigkeit zugunsten des Wohlergehens all unserer Mitarbeiter und unserer Anteilseigner.<\/p>\n<\/p>\n<h3 style=\"color: #527d77; font-weight: 400; letter-spacing: 3px; font-family: 'EB Garamond' ,serif;\">14. Dauer, f\u00fcr die die personenbezogenen Daten gespeichert werden<\/h3>\n<p>Das Kriterium f\u00fcr die Dauer der Speicherung von personenbezogenen Daten ist die jeweilige gesetzliche Aufbewahrungsfrist. Nach Ablauf der Frist werden die entsprechenden Daten routinem\u00e4\u00dfig gel\u00f6scht, sofern sie nicht mehr zur Vertragserf\u00fcllung oder Vertragsanbahnung erforderlich sind.<\/p>\n<\/p>\n<p>15. Gesetzliche oder vertragliche Vorschriften zur Bereitstellung der personenbezogenen Daten; Erforderlichkeit f\u00fcr den Vertragsabschluss; Verpflichtung der betroffenen Person, die personenbezogenen Daten bereitzustellen; m\u00f6gliche Folgen der Nichtbereitstellung<\/p>\n<\/p>\n<p>Wir kl\u00e4ren Sie dar\u00fcber auf, dass die Bereitstellung personenbezogener Daten zum Teil gesetzlich vorgeschrieben ist (z.B. Steuervorschriften) oder sich auch aus vertraglichen Regelungen (z.B. Angaben zum Vertragspartner) ergeben kann. Mitunter kann es zu einem Vertragsschluss erforderlich sein, dass eine betroffene Person uns personenbezogene Daten zur Verf\u00fcgung stellt, die in der Folge durch uns verarbeitet werden m\u00fcssen. Die betroffene Person ist beispielsweise verpflichtet uns personenbezogene Daten bereitzustellen, wenn unser Unternehmen mit ihr einen Vertrag abschlie\u00dft. Eine Nichtbereitstellung der personenbezogenen Daten h\u00e4tte zur Folge, dass der Vertrag mit dem Betroffenen nicht geschlossen werden k\u00f6nnte. Vor einer Bereitstellung personenbezogener Daten durch den Betroffenen muss sich der Betroffene an unseren Datenschutzbeauftragten wenden. Unser Datenschutzbeauftragter kl\u00e4rt den Betroffenen einzelfallbezogen dar\u00fcber auf, ob die Bereitstellung der personenbezogenen Daten gesetzlich oder vertraglich vorgeschrieben oder f\u00fcr den Vertragsabschluss erforderlich ist, ob eine Verpflichtung besteht, die personenbezogenen Daten bereitzustellen, und welche Folgen die Nichtbereitstellung der personenbezogenen Daten h\u00e4tte.<\/p>\n<\/p>\n<h3 style=\"color: #527d77; font-weight: 400; letter-spacing: 3px; font-family: 'EB Garamond' ,serif;\">16. Bestehen einer automatisierten Entscheidungsfindung<\/h3>\n<p>Als verantwortungsbewusstes Unternehmen verzichten wir auf eine automatische Entscheidungsfindung oder ein Profiling.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Datenschutz Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung der 24h Safe GmbH. Eine Nutzung der Internetseiten der 24h Safe GmbH ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2799,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-2853","page","type-page","status-publish","has-post-thumbnail","hentry"],"blocksy_meta":{"page_title_panel":"","has_hero_section":"disabled","3a591669c17ecbe5ad9620896e1211bd":"","hero_section":"type-1","hero_elements":[{"id":"custom_title","enabled":true,"heading_tag":"h1","title":"Home"},{"id":"custom_description","enabled":true,"description_visibility":{"desktop":true,"tablet":true,"mobile":false}},{"id":"custom_meta","enabled":false,"meta_elements":[{"id":"author","enabled":true,"label":"By","has_author_avatar":"yes","avatar_size":25},{"id":"post_date","enabled":true,"label":"On","date_format_source":"default","date_format":"M j, Y"},{"id":"updated_date","enabled":false,"label":"On","date_format_source":"default","date_format":"M j, Y"},{"id":"categories","enabled":false,"label":"In","style":"simple"},{"id":"comments","enabled":true}],"page_meta_elements":{"joined":true,"articles_count":true,"comments":true}},{"id":"breadcrumbs","enabled":false}],"f5f2ba01ee359499f32ab5c653bb37ae":"","hero_alignment1":"CT_CSS_SKIP_RULE","hero_margin":40,"hero_alignment2":"center","hero_vertical_alignment":"center","26df382601c89d835b317d28c4181d5c":"","hero_structure":"narrow","e8d1a46f9f1093303dae3e32eed4ca12":"","page_title_bg_type":"featured_image","custom_hero_background":{"attachment_id":null},"page_title_image_size":"full","parallax":{"desktop":false,"tablet":false,"mobile":false},"c91b04957ac05d0f4b1f79196a104b0b":"","hero_height":"250px","pageTitleFont":{"family":"Default","variation":"Default","size":"30px","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"pageTitleFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageMetaFont":{"family":"Default","variation":"n6","size":"12px","line-height":"1.3","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"uppercase","text-decoration":"CT_CSS_SKIP_RULE"},"pageMetaFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"page_meta_button_type_font_colors":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"page_meta_button_type_background_colors":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageExcerptFont":{"family":"Default","variation":"Default","size":"CT_CSS_SKIP_RULE","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"pageExcerptColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"breadcrumbsFont":{"family":"Default","variation":"Default","size":"CT_CSS_SKIP_RULE","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"breadcrumbsFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"initial":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageTitleOverlay":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"CT_CSS_SKIP_RULE"}}},"pageTitleBackground":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"var(--theme-palette-color-6)"}}},"pageTitlePadding":{"top":"50px","bottom":"50px","left":"auto","right":"auto","linked":true},"576686a59b9e7267bd2d8fec0d8fe65a":"","page_structure_type":"default","f7b63f64a17c8968a763323238a09c39":"","content_style_source":"inherit","content_style":"wide","vertical_spacing_source":"custom","content_area_spacing":"none","background":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"CT_CSS_SKIP_RULE"}}},"content_background":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"var(--theme-palette-color-8)"}}},"content_boxed_shadow":{"inherit":false,"blur":18,"spread":-6,"v_offset":12,"h_offset":0,"inset":false,"enable":true,"color":{"color":"rgba(34, 56, 101, 0.04)"}},"content_boxed_border":{"width":1,"style":"none","color":{"color":"rgba(44,62,80,0.2)"}},"content_boxed_radius":{"top":"3px","bottom":"3px","left":"3px","right":"3px","linked":true},"boxed_content_spacing":{"desktop":{"top":"40px","bottom":"40px","left":"40px","right":"40px","linked":true},"tablet":{"top":"35px","bottom":"35px","left":"35px","right":"35px","linked":true},"mobile":{"top":"20px","bottom":"20px","left":"20px","right":"20px","linked":true}},"6454d985ee384fc436d23b0f5e1a2159":"","disable_featured_image":"no","disable_share_box":"no","disable_header":"no","disable_footer":"no","styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy Tresor am Schottentor. 24\/7 safe Vienna<\/title>\n<meta name=\"description\" content=\"Privacy policy Tresor am Schottentor. The secure &amp; bank-independent safe deposit box with 24\/7 access in Vienna. 24h Safe GmbH, Vienna.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tresoramschottentor.at\/en\/privacy\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy Tresor am Schottentor. 24\/7 safe Vienna\" \/>\n<meta property=\"og:description\" content=\"Privacy policy Tresor am Schottentor. The secure &amp; bank-independent safe deposit box with 24\/7 access in Vienna. 24h Safe GmbH, Vienna.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tresoramschottentor.at\/en\/privacy\/\" \/>\n<meta property=\"og:site_name\" content=\"Tresor am Schottentor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tresoramschottentor\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-30T09:09:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tresoramschottentor.at\/wp-content\/uploads\/2022\/08\/csm__DSC6847_5110e8b3c5.jpg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"991\" \/>\n\t<meta property=\"og:image:height\" content=\"661\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"27 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tresoramschottentor.at\\\/en\\\/privacy\\\/\",\"url\":\"https:\\\/\\\/tresoramschottentor.at\\\/en\\\/privacy\\\/\",\"name\":\"Privacy Policy Tresor am Schottentor. 24\\\/7 safe Vienna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tresoramschottentor.at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tresoramschottentor.at\\\/en\\\/privacy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tresoramschottentor.at\\\/en\\\/privacy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tresoramschottentor.at\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/6_Sicherheit.svg\",\"datePublished\":\"2022-08-24T14:27:00+00:00\",\"dateModified\":\"2024-08-30T09:09:08+00:00\",\"description\":\"Privacy policy Tresor am Schottentor. The secure & bank-independent safe deposit box with 24\\\/7 access in Vienna. 24h Safe GmbH, Vienna.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tresoramschottentor.at\\\/en\\\/privacy\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tresoramschottentor.at\\\/en\\\/privacy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/tresoramschottentor.at\\\/en\\\/privacy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tresoramschottentor.at\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/6_Sicherheit.svg\",\"contentUrl\":\"https:\\\/\\\/tresoramschottentor.at\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/6_Sicherheit.svg\",\"width\":504,\"height\":504,\"caption\":\"Datenschutz Tresor am Schottentor; Sicherheit - Icon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tresoramschottentor.at\\\/en\\\/privacy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/tresoramschottentor.at\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tresoramschottentor.at\\\/#website\",\"url\":\"https:\\\/\\\/tresoramschottentor.at\\\/\",\"name\":\"Schlie\u00dffach mieten 24\\\/7 Zutritt Tresor am Schottentor Wien\",\"description\":\"Sicheres Schlie\u00dffach mieten in Wien\",\"publisher\":{\"@id\":\"https:\\\/\\\/tresoramschottentor.at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tresoramschottentor.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tresoramschottentor.at\\\/#organization\",\"name\":\"Tresor am Schottentor\",\"alternateName\":\"24H Safe GmbH\",\"url\":\"https:\\\/\\\/tresoramschottentor.at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/tresoramschottentor.at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tresoramschottentor.at\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/tresor_am_schottentor_klein.jpg\",\"contentUrl\":\"https:\\\/\\\/tresoramschottentor.at\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/tresor_am_schottentor_klein.jpg\",\"width\":2338,\"height\":2338,\"caption\":\"Tresor am Schottentor\"},\"image\":{\"@id\":\"https:\\\/\\\/tresoramschottentor.at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tresoramschottentor\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tresor-am-schottentor\\\/\",\"https:\\\/\\\/www.instagram.com\\\/tresoramschottentor\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy Tresor am Schottentor. 24\/7 safe Vienna","description":"Privacy policy Tresor am Schottentor. The secure & bank-independent safe deposit box with 24\/7 access in Vienna. 24h Safe GmbH, Vienna.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tresoramschottentor.at\/en\/privacy\/","og_locale":"en_US","og_type":"article","og_title":"Privacy Policy Tresor am Schottentor. 24\/7 safe Vienna","og_description":"Privacy policy Tresor am Schottentor. The secure & bank-independent safe deposit box with 24\/7 access in Vienna. 24h Safe GmbH, Vienna.","og_url":"https:\/\/tresoramschottentor.at\/en\/privacy\/","og_site_name":"Tresor am Schottentor","article_publisher":"https:\/\/www.facebook.com\/tresoramschottentor","article_modified_time":"2024-08-30T09:09:08+00:00","og_image":[{"width":991,"height":661,"url":"https:\/\/tresoramschottentor.at\/wp-content\/uploads\/2022\/08\/csm__DSC6847_5110e8b3c5.jpg.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"27 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tresoramschottentor.at\/en\/privacy\/","url":"https:\/\/tresoramschottentor.at\/en\/privacy\/","name":"Privacy Policy Tresor am Schottentor. 24\/7 safe Vienna","isPartOf":{"@id":"https:\/\/tresoramschottentor.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tresoramschottentor.at\/en\/privacy\/#primaryimage"},"image":{"@id":"https:\/\/tresoramschottentor.at\/en\/privacy\/#primaryimage"},"thumbnailUrl":"https:\/\/tresoramschottentor.at\/wp-content\/uploads\/2022\/08\/6_Sicherheit.svg","datePublished":"2022-08-24T14:27:00+00:00","dateModified":"2024-08-30T09:09:08+00:00","description":"Privacy policy Tresor am Schottentor. The secure & bank-independent safe deposit box with 24\/7 access in Vienna. 24h Safe GmbH, Vienna.","breadcrumb":{"@id":"https:\/\/tresoramschottentor.at\/en\/privacy\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tresoramschottentor.at\/en\/privacy\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tresoramschottentor.at\/en\/privacy\/#primaryimage","url":"https:\/\/tresoramschottentor.at\/wp-content\/uploads\/2022\/08\/6_Sicherheit.svg","contentUrl":"https:\/\/tresoramschottentor.at\/wp-content\/uploads\/2022\/08\/6_Sicherheit.svg","width":504,"height":504,"caption":"Datenschutz Tresor am Schottentor; Sicherheit - Icon"},{"@type":"BreadcrumbList","@id":"https:\/\/tresoramschottentor.at\/en\/privacy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/tresoramschottentor.at\/en\/"},{"@type":"ListItem","position":2,"name":"Datenschutz"}]},{"@type":"WebSite","@id":"https:\/\/tresoramschottentor.at\/#website","url":"https:\/\/tresoramschottentor.at\/","name":"Schlie\u00dffach mieten 24\/7 Zutritt Tresor am Schottentor Wien","description":"Sicheres Schlie\u00dffach mieten in Wien","publisher":{"@id":"https:\/\/tresoramschottentor.at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tresoramschottentor.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/tresoramschottentor.at\/#organization","name":"Tresor am Schottentor","alternateName":"24H Safe GmbH","url":"https:\/\/tresoramschottentor.at\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tresoramschottentor.at\/#\/schema\/logo\/image\/","url":"https:\/\/tresoramschottentor.at\/wp-content\/uploads\/2022\/09\/tresor_am_schottentor_klein.jpg","contentUrl":"https:\/\/tresoramschottentor.at\/wp-content\/uploads\/2022\/09\/tresor_am_schottentor_klein.jpg","width":2338,"height":2338,"caption":"Tresor am Schottentor"},"image":{"@id":"https:\/\/tresoramschottentor.at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tresoramschottentor","https:\/\/www.linkedin.com\/company\/tresor-am-schottentor\/","https:\/\/www.instagram.com\/tresoramschottentor\/"]}]}},"_links":{"self":[{"href":"https:\/\/tresoramschottentor.at\/en\/wp-json\/wp\/v2\/pages\/2853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tresoramschottentor.at\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tresoramschottentor.at\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tresoramschottentor.at\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tresoramschottentor.at\/en\/wp-json\/wp\/v2\/comments?post=2853"}],"version-history":[{"count":0,"href":"https:\/\/tresoramschottentor.at\/en\/wp-json\/wp\/v2\/pages\/2853\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tresoramschottentor.at\/en\/wp-json\/wp\/v2\/media\/2799"}],"wp:attachment":[{"href":"https:\/\/tresoramschottentor.at\/en\/wp-json\/wp\/v2\/media?parent=2853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}